{"id":1157,"date":"2025-02-25T22:57:19","date_gmt":"2025-02-26T02:57:19","guid":{"rendered":"https:\/\/jockeypronosticos.com\/?p=1157"},"modified":"2025-02-25T22:57:19","modified_gmt":"2025-02-26T02:57:19","slug":"el-emperador-de-los-aciertos-79","status":"publish","type":"post","link":"https:\/\/jockeypronosticos.com\/index.php\/2025\/02\/25\/el-emperador-de-los-aciertos-79\/","title":{"rendered":"El Emperador de los Aciertos"},"content":{"rendered":"\n<p>Rigoberto Palencia el \u00abEmperador de los Aciertos\u00bb comparte su informaci\u00f3n con todos nosotros:<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/jockeypronosticos.com\/wp-content\/uploads\/2025\/02\/RPalencia25225.m4a\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Rigoberto Palencia el \u00abEmperador de los Aciertos\u00bb comparte su informaci\u00f3n con todos nosotros:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1157","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/posts\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":1,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"predecessor-version":[{"id":1159,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/posts\/1157\/revisions\/1159"}],"wp:attachment":[{"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jockeypronosticos.com\/index.php\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}